{"id":84748,"date":"2025-12-03T10:09:36","date_gmt":"2025-12-03T03:09:36","guid":{"rendered":"https:\/\/mbrellafilms.com\/insights\/korean-dramas-filmed-in-thailand\/"},"modified":"2026-08-24T10:10:03","modified_gmt":"2026-08-24T03:10:03","slug":"korean-dramas-filmed-in-thailand","status":"publish","type":"insights","link":"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/","title":{"rendered":"19 dramas coreanos (K-Dramas) filmados en Tailandia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A lo largo de los a\u00f1os, Tailandia se ha convertido en un destino principal para las producciones coreanas que buscan entornos de filmaci\u00f3n llamativos, vers\u00e1tiles y culturalmente ricos. Desde hoteles de lujo y playas v\u00edrgenes hasta paisajes urbanos vibrantes, mercados bulliciosos y exuberantes cadenas monta\u00f1osas, el pa\u00eds ofrece una variedad excepcional de telones de fondo que elevan la narrativa visual de los K-dramas en ascenso. Desde su auge de popularidad a principios de la d\u00e9cada de 2000, los K-dramas contin\u00faan expandi\u00e9ndose a nivel mundial, y el atractivo cinematogr\u00e1fico de Tailandia solo se ha fortalecido en respuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 es Tailandia una opci\u00f3n tan atractiva para las series coreanas? M\u00e1s all\u00e1 de sus diversas ubicaciones, el gobierno tailand\u00e9s ofrece atractivos incentivos de reembolso en efectivo de hasta el 30% para apoyar a los equipos de producci\u00f3n internacionales y maximizar su potencial creativo. Mbrella Films, con sede en Bangkok, mejora a\u00fan m\u00e1s este atractivo, proporcionando equipos multiculturales, de habla inglesa y altamente calificados, y un apoyo integral en cada etapa del proceso de producci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un flujo de trabajo eficiente impulsado por los mejores profesionales de la industria de Tailandia, las producciones de dramas coreanos pueden pasar de la planificaci\u00f3n a la ejecuci\u00f3n con una velocidad, calidad y pulido notables.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Gold Land (2026)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/gold-land-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-87689\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/gold-land-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/gold-land-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/gold-land-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/gold-land-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Tierra de oro<\/em> es un nuevo thriller criminal de 10 episodios que se estrena en Disney+ y Hulu, y sigue a Kim Hee-ju (Park Bo-young), una agente de seguridad aeroportuaria cuyo novio, un piloto, la arrastra a un esquema de contrabando de oro dirigido por una organizaci\u00f3n criminal oculta. Lo que comienza como una mala decisi\u00f3n se convierte en una historia de codicia, tensi\u00f3n, traici\u00f3n y peligro, mientras ella se ve arrastrada a la \u00f3rbita de personas cada vez m\u00e1s peligrosas. La serie se estren\u00f3 el 29 de abril de 2026 y est\u00e1 protagonizada por Park Bo-young, Kim Sung-cheol, Lee Hyun-wook, Kim Hee-won, Moon Jung-hee y Lee Kwang-soo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parte de la producci\u00f3n se rod\u00f3 en Tailandia, aunque no se revelaron p\u00fablicamente las ubicaciones de rodaje. Una empresa tailandesa local proporcion\u00f3 servicios de iluminaci\u00f3n y grip para la unidad de rodaje en Tailandia.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">M\u00e1s informaci\u00f3n sobre la producci\u00f3n de dramas coreanos en Tailandia<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2. A Shop for Killers 2 (2026)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/a-shop-for-killers-2-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-87698\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/a-shop-for-killers-2-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/a-shop-for-killers-2-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/a-shop-for-killers-2-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/a-shop-for-killers-2-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Negocio letal 2<\/em> es un thriller de acci\u00f3n coreano basado en la novela de Kang Ji-young. Sigue a Jung Ji-an, una estudiante universitaria que descubre que su difunto t\u00edo, Jung Jin-man, dirig\u00eda en secreto \u00abMurthehelp\u00bb, un mercado de la dark web que suministraba armas a asesinos. En la segunda temporada, Ji-an ha asumido el cargo de directora general de Murthehelp y se une a Jin-man para derrotar a Babylon, una organizaci\u00f3n global de asesinos, antes de que sea demasiado tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo de rodaje film\u00f3 en Tailandia en noviembre de 2025, en cinco provincias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asok Montri Intersection, Bangkok<\/li>\n\n\n\n<li>Imperial World Samrong, Samut Prakan<\/li>\n\n\n\n<li>Khao Yai National Park, Nakhon Ratchasima<\/li>\n\n\n\n<li>Saphan Lao Community Forest (Thong Pha Phum District), Kanchanaburi<\/li>\n\n\n\n<li>Tang Sia Huat Market (Mueang Nakhon Pathom District), Nakhon Pathom<\/li>\n\n\n\n<li>Wat Thaiyawat (Nakhon Chai Si District), Nakhon Pathom<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">M\u00e1s informaci\u00f3n sobre la producci\u00f3n de dramas coreanos en Tailandia<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3. The Price of Confession (2025)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/price-of-confession-cover-image-2-1024x536.jpg\" alt=\"\" class=\"wp-image-84979\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/price-of-confession-cover-image-2-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/price-of-confession-cover-image-2-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/price-of-confession-cover-image-2-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/price-of-confession-cover-image-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las series m\u00e1s populares de 2025 es Price of Confession. A una mujer acusada de matar a su marido se le ofrece un trato, pero aceptarlo significa que debe cometer un asesinato. Esta trepidante serie destaca como un tenso drama criminal con partes iguales de misterio y thriller.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proporcionamos apoyo de producci\u00f3n durante todo el rodaje en Tailandia, incluyendo equipo local, un director de arte, log\u00edstica, alojamiento y SFX. Nuestros servicios dieron soporte a los 75 miembros del equipo coreano que viajaron desde Corea del Sur para el rodaje. Adem\u00e1s, brindamos apoyo de preproducci\u00f3n asistiendo con la b\u00fasqueda de locaciones y la obtenci\u00f3n de permisos, as\u00ed como con el casting de m\u00e1s de 200 extras de fondo y destacados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rodaje tuvo lugar en Chiang Mai y Chiang Rai. Estas locaciones incluyeron Baan Pa Ka Homestay &amp; Camping, Aoyama Border Patrol Police School, Tangerine Ville Hotel y Sleeping Tree Hotel, todos en Chiang Mai. En Chiang Rai, el equipo film\u00f3 en Ban Nong Pla Sadet.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">M\u00e1s informaci\u00f3n sobre la producci\u00f3n de dramas coreanos en Tailandia<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4. Made in Korea (2025)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/made-in-korea-cover-image-2-1024x536.jpg\" alt=\"\" class=\"wp-image-84952\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/made-in-korea-cover-image-2-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/made-in-korea-cover-image-2-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/made-in-korea-cover-image-2-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/12\/made-in-korea-cover-image-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con su estreno en Disney+ el 24 de diciembre de 2025, Made in Korea es un drama criminal y pol\u00edtico de \u00e9poca ambientado en la Corea del Sur de la d\u00e9cada de 1970. La serie enfrenta a Baek Ki-tae (interpretado por Hyun Bin), un ambicioso agente de la KCIA que construye poder en secreto a trav\u00e9s de redes il\u00edcitas, contra el fiscal Jang Geon-young (interpretado por Jung Woo-sung), quien est\u00e1 decidido a derribarlo, sin importar el costo personal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro equipo proporcion\u00f3 servicios completos de producci\u00f3n durante todo el rodaje en Tailandia, incluyendo b\u00fasqueda de locaciones, permisos de filmaci\u00f3n, SFX, asistencia de direcci\u00f3n, coordinaci\u00f3n de arte, log\u00edstica y catering. Los servicios apoyaron a 85 miembros del equipo extranjero y a m\u00e1s de 150 miembros del equipo tailand\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La serie se film\u00f3 en varias locaciones de Kanchanaburi y Chonburi. Estos lugares incluyeron el T\u00fanel 3D, Sangchuto Road, la playa Satthahip y el Cuerpo de la Base Naval Real de Tailandia en Chonburi.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">M\u00e1s informaci\u00f3n sobre la producci\u00f3n de dramas coreanos en Tailandia<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">5. Typhoon Family (2025)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/typhoon-family-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84567\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/typhoon-family-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/typhoon-family-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/typhoon-family-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/typhoon-family-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los \u00e9xitos destacados de K-drama de este a\u00f1o es <em>Typhoon Family<\/em>, protagonizado por Lee Jun-ho de 2PM y la aclamada actriz Kim Min-ha. Apareciendo como cameo, est\u00e1 la actriz tailandesa Mai Davika, quien interpreta a Nicha, apareciendo junto a Lee Jun Ho en la serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La historia sigue a Ke Tae Poong mientras asume el control de la empresa de su padre. Mientras se esfuerza por proteger el negocio, se encuentra navegando desaf\u00edos crecientes en medio de la turbulenta crisis financiera del FMI de 1997.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una gran parte de la serie se film\u00f3 en Tailandia durante un per\u00edodo de producci\u00f3n de cuatro semanas, abarcando Bangkok, Samut Prakan, Phuket y Chiang Mai. Las ubicaciones de rodaje en Bangkok incluyen The Peninsula Bangkok, The Coach Hotel Sukhumvit, Yaowarat Road (Chinatown) y un almac\u00e9n junto al r\u00edo cerca del puerto de Rama III. Se capturaron secuencias adicionales en Samut Prakan, Phuket y Chiang Mai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varios miembros del elenco tambi\u00e9n fueron vistos filmando en Cape Yamu Resort &amp; Villas en Phuket, cuyos espacios interiores se utilizaron para retratar el lujoso entorno residencial del programa.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">M\u00e1s informaci\u00f3n sobre la producci\u00f3n de dramas coreanos en Tailandia<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">6. The Fiery Priest 2 (2024)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fiery-priest-2-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84522\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fiery-priest-2-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fiery-priest-2-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fiery-priest-2-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fiery-priest-2-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>The Fiery Priest 2<\/em> film\u00f3 partes de su arco en el extranjero en Tailandia durante junio y julio de 2024, marcando el primer rodaje importante de la producci\u00f3n en el pa\u00eds. El elenco y el equipo fueron vistos en Bangkok y las regiones circundantes mientras escenificaban secuencias cargadas de acci\u00f3n destinadas a expandir la trama criminal internacional del programa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Bangkok, el rodaje tuvo lugar en densas zonas urbanas y calles laterales a menudo utilizadas para configuraciones de persecuci\u00f3n, mientras que Samut Prakan proporcion\u00f3 telones de fondo industriales: bloques de almacenes, carreteras portuarias y patios de contenedores que se ajustaban al tono. El equipo tambi\u00e9n film\u00f3 en Khao Yai, utilizando el terreno boscoso y las carreteras rurales del parque nacional para escenas de persecuci\u00f3n y secuencias de escondites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, dobles de riesgo y equipo locales tailandeses se unieron a la producci\u00f3n, y varios avistamientos detr\u00e1s de escena desde junio y principios de julio confirmaron el rodaje en el lugar antes de que SBS reconociera m\u00e1s tarde a Tailandia como uno de los sitios internacionales del drama.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">7. Love in the Big City (2024)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/love-in-the-big-city-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84495\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/love-in-the-big-city-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/love-in-the-big-city-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/love-in-the-big-city-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/love-in-the-big-city-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las series BL m\u00e1s destacadas de 2024 es<em> Love in the Big City<\/em>, que sigue a un joven gay navegando por las complejidades del romance, la identidad y la din\u00e1mica cambiante de su amistad con su compa\u00f1era de cuarto heterosexual, Choi Mi-ae. La serie destaca por su representaci\u00f3n fundamentada de la vida queer, capturando el espectro emocional del amor, la soledad y el autodescubrimiento. Buscando claridad y un nuevo comienzo, Go Young viaja a Tailandia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mbrella Films proporcion\u00f3 apoyo de producci\u00f3n a gran escala durante el rodaje en Tailandia. Los servicios incluyeron asegurar alojamiento y transporte, suministrar equipos de seguridad dedicados para el elenco y coordinar la log\u00edstica para casi 50 miembros del equipo coreano. Durante la preproducci\u00f3n, Mbrella Films tambi\u00e9n ayud\u00f3 con la b\u00fasqueda de ubicaciones y permisos, seleccion\u00f3 a m\u00e1s de 300 extras de fondo y destacados, y entreg\u00f3 apoyo de dise\u00f1o de producci\u00f3n en todos los sitios de filmaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La serie se film\u00f3 en varias ubicaciones clave, incluyendo el MBK Center, el r\u00edo Chao Phraya, Park Hyatt Bangkok en Central Embassy, SPEED CLUB BKK, Baan Channasongkram Hostel y sitios adicionales en toda la ciudad.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">8. The Player 2: Master of Swindlers (2024)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-player-2-master-of-swindlers-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84558\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-player-2-master-of-swindlers-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-player-2-master-of-swindlers-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-player-2-master-of-swindlers-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-player-2-master-of-swindlers-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este drama de acci\u00f3n y atracos re\u00fane a un equipo de \u00e9lite de especialistas: estafadores, hackers, luchadores y conductores unidos por una sola misi\u00f3n: rastrear y robar la riqueza il\u00edcita acumulada por los poderosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rodaje tuvo lugar en Tailandia de septiembre a noviembre de 2023, abarcando m\u00faltiples ciudades, incluyendo Bangkok, Pattaya, Ayutthaya y Phuket. En Bangkok, las ubicaciones clave incluyeron el distrito de Sathorn, donde la producci\u00f3n utiliz\u00f3 un hotel de lujo con un bar en la azotea. Yaowarat (Chinatown) tambi\u00e9n apareci\u00f3 de manera destacada, con el equipo coreano importando letreros personalizados para mezclar los escaparates coreanos en el paisaje urbano local. Rodaje adicional ocurri\u00f3 en la estaci\u00f3n de tren de Hua Lamphong y en ICONSIAM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Pattaya, la producci\u00f3n se film\u00f3 en Terminal 21, destacando la ic\u00f3nica instalaci\u00f3n de avi\u00f3n del centro comercial en la entrada. Las secuencias de Phuket incluyeron Cape Panwa, la playa de Ao Yon y vistas a\u00e9reas del casco antiguo de Phuket, mostrando la diversidad esc\u00e9nica de la isla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno tailand\u00e9s apoy\u00f3 activamente el rodaje como parte de una campa\u00f1a tur\u00edstica m\u00e1s amplia. Hasta la fecha, este proyecto es considerado como una de las secuencias de filmaci\u00f3n en el extranjero m\u00e1s caras para un K-drama en 2023.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">9. King the Land (2023)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/king-the-land-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84486\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/king-the-land-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/king-the-land-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/king-the-land-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/king-the-land-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>King the Land<\/em> sigue a Gu Won, interpretado por Lee Jun-ho, heredero de The King Group, un conglomerado de hoteles de lujo atrapado en una intensa batalla por la herencia. Su mundo cambia cuando conoce a Cheon Sa-rang, interpretada por Im Yoon-ah, una hotelera dedicada conocida como la querida \u00abreina de la sonrisa\u00bb del King Hotel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mbrella Films ayud\u00f3 con servicios de producci\u00f3n completos durante toda la etapa de Tailandia del rodaje. El equipo coordin\u00f3 alojamiento, transporte, seguridad, permisos de trabajo y permisos de ubicaci\u00f3n, al tiempo que entregaba un apoyo log\u00edstico integral para casi 90 miembros del equipo coreano. M\u00e1s all\u00e1 de la asistencia de producci\u00f3n est\u00e1ndar, Mbrella Films cre\u00f3 un espacio de festival personalizado a lo largo del ic\u00f3nico paseo mar\u00edtimo de ICONSIAM y transform\u00f3 el canal Ong Ang a trav\u00e9s de redecoraciones adaptadas al tono y estilo visual de la serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ubicaciones de rodaje populares en Tailandia incluyeron varios de los sitios m\u00e1s renombrados de Tailandia: Wat Arun (Templo del Amanecer), Vertigo Rooftop en el Banyan Tree Hotel, Siri Sala Private Thai Villa y la Ciudad Antigua (Muang Boran). Ubicaciones adicionales en Bangkok que aparecieron en la serie incluyen Asiatique The Riverfront, ICONSIAM, el canal Ong Ang y Khao San Road.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">10. Bloodhounds (2023)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/bloodhounds-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84459\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/bloodhounds-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/bloodhounds-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/bloodhounds-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/bloodhounds-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Bloodhound<\/em> sigue a un joven boxeador que une fuerzas con un delincuente y un prestamista para acabar con una despiadada organizaci\u00f3n de usureros. Repleto de acci\u00f3n explosiva, atracos crudos y combates de boxeo llenos de adrenalina, el programa mantiene a los espectadores al borde de sus asientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los episodios 5 y 6 se filmaron en Tailandia a finales de 2022, con Bangkok sirviendo como tel\u00f3n de fondo principal. Las ubicaciones clave incluyeron Yaowarat Road (Chinatown), Sukhumvit Soi 11, Soi Cowboy, varias \u00e1reas ribere\u00f1as y los muelles del Chao Phraya. Una de las secuencias destacadas, la persecuci\u00f3n en moto en el Episodio 5, fue filmada en la intersecci\u00f3n Chaloen Buri cerca de Wat Traimit, un rinc\u00f3n vibrante de Chinatown conocido por su energ\u00eda bulliciosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La producci\u00f3n tambi\u00e9n adapt\u00f3 interiores de clubes en Sukhumvit Soi 11, notablemente Insanity y Sugar Club, remodelando los lugares para que se ajustaran al tono y la est\u00e9tica de la serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Pathum Thani, la gran pelea en el almac\u00e9n y la acrobacia de fuego se filmaron en una zona industrial al norte de Bangkok, un sitio utilizado frecuentemente por producciones internacionales para explosiones controladas y trabajo de acrobacias de alto riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo tambi\u00e9n captur\u00f3 escenas breves en Pattaya, principalmente alrededor de la playa Jomtien y el centro comercial Terminal 21.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">11. Run On (2020)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/run-on-cover-new-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84586\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/run-on-cover-new-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/run-on-cover-new-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/run-on-cover-new-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/run-on-cover-new-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una historia de amor se desarrolla entre Ki Seon-gyeom (Yim Si-wan), un ex velocista que finalmente aprende a seguir su coraz\u00f3n, y Oh Mi-joo (Shin Sae-kyeong), una traductora de cine que cambia su vida en el momento en que entra en ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Run On<\/em> comenz\u00f3 a filmarse en febrero-marzo de 2020, justo antes de que se cerraran las fronteras internacionales. La producci\u00f3n pas\u00f3 aproximadamente diez d\u00edas filmando en Tailandia con el apoyo de alrededor de 40 miembros del equipo local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rodaje tuvo lugar en Bangkok y Chiang Mai. En Bangkok, se capturaron escenas en la terraza del r\u00edo de ICONSIAM y a lo largo de la orilla del r\u00edo Chao Phraya, con el Millennium Hilton destacado prominentemente al otro lado del agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Chiang Mai, la producci\u00f3n utiliz\u00f3 m\u00faltiples lugares pintorescos: el complejo de ladrillo rojo One Nimman en Nimmanhaemin Road, Ristr8to Coffee, Chic 39 Hotel, Wat Phra Singh Woramahawihan y Wat Chedi Luang. Escenas adicionales se filmaron en el campo de Mae Rim a lo largo de la carretera rural Mae Rim 4024 cerca del mirador Mon Cham.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secuencias de drones filmadas durante la hora dorada siguieron a los actores a trav\u00e9s de paisajes extensos, pintando la serie en c\u00e1lidos e impresionantes campos dorados.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">12. Vagabond (2019)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/vagabond-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84576\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/vagabond-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/vagabond-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/vagabond-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/vagabond-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Vagabond <\/em>sigue a Cha Dal Geon (interpretado por Lee Seung-gi), un doble de acci\u00f3n altamente calificado pero subvalorado cuya vida se ve desarraigada cuando ocurre una tragedia. Mientras equilibra las demandas de su carrera en ascenso, tambi\u00e9n sirve como tutor de su sobrino, Cha Hoon (Moon Woo-jin). Pero cuando Hoon viaja al extranjero para una exhibici\u00f3n de taekwondo y el avi\u00f3n se estrella misteriosamente, Dal Geon se convence de que el incidente no fue un accidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Impulsado por el dolor y la sospecha, comienza su propia investigaci\u00f3n, cruz\u00e1ndose finalmente con Go Hae Ri (Bae Suzy), una agente del NIS que opera encubierta en la embajada de Corea en Marruecos. Juntos, desentra\u00f1an un rastro de agendas ocultas, operativos sombr\u00edos y una conspiraci\u00f3n mucho m\u00e1s peligrosa de lo que cualquiera de los dos esperaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rodaje tuvo lugar entre enero y febrero de 2019, con el equipo de producci\u00f3n haciendo paradas clave en Bangkok, Chiang Mai y Pattaya. Tailandia sirvi\u00f3 como un sustituto pr\u00e1ctico de Marruecos gracias a su iluminaci\u00f3n compatible, caracter\u00edsticas arquitect\u00f3nicas y viabilidad general en costos y log\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Bangkok, el Aeropuerto Internacional Don Mueang se transform\u00f3 en el aeropuerto marroqu\u00ed que aparece en los episodios iniciales. Los equipos instalaron se\u00f1alizaci\u00f3n en \u00e1rabe y organizaron multitudes de turistas y funcionarios para replicar el entorno. Los mercados de callejones estrechos de Chinatown se utilizaron para secuencias de persecuci\u00f3n y seguimiento, mientras que escenas nocturnas adicionales involucraron veh\u00edculos de embajada simulados y bloqueos de tr\u00e1fico controlados. Cerca del Parque Lumpini, se film\u00f3 una persecuci\u00f3n de autos de alta intensidad con un SUV negro, completa con explosiones cuidadosamente coordinadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ciudad Vieja de Chiang Mai se adapt\u00f3 a un bullicioso mercado marroqu\u00ed, donde los escaparates tailandeses se ocultaron bajo pancartas con escritura \u00e1rabe y accesorios. El distrito de Mae Rim, particularmente la carretera que conduce hacia las monta\u00f1as, proporcion\u00f3 el tel\u00f3n de fondo para la fotograf\u00eda a\u00e9rea y escenas de persecuci\u00f3n en carretera dise\u00f1adas para parecerse al terreno del norte de \u00c1frica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de 120 miembros del equipo tailand\u00e9s apoyaron el proyecto, muchos de los cuales trabajaron anteriormente en grandes producciones internacionales, incluyendo <em>Extraction 2<\/em> y <em>The Hangover Part II<\/em>.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">13. It\u2019s Okay to be Sensitive 2 (2019)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/its-okay-to-be-sensitive-2-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84450\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/its-okay-to-be-sensitive-2-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/its-okay-to-be-sensitive-2-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/its-okay-to-be-sensitive-2-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/its-okay-to-be-sensitive-2-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>It\u2019s Okay to Be Sensitive 2<\/em>, un drama corto de YouTube, film\u00f3 varias escenas clave en Tailandia, con la producci\u00f3n movi\u00e9ndose entre Bangkok y Hua Hin para capturar mercados, impresionantes telones de fondo y entornos costeros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Bangkok, el mercado de Chatujak aparece en breves cortes de montaje, mientras que los caf\u00e9s alrededor del distrito de Ari se utilizaron para momentos casuales de los personajes. Secuencias de caminata se filmaron a lo largo de Soi Chulalongkorn 42, donde el elenco pasa por coloridas paredes de graffiti pertenecientes a HOF Art Space Bangkok, confirmado por la galer\u00eda en Instagram despu\u00e9s de recibir al equipo de tvN por un d\u00eda. Una serie de tomas generales tambi\u00e9n captura el horizonte del r\u00edo Chao Phraya, probablemente filmadas desde un barco cerca de ICONSIAM o el muelle Asiatique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s al sur en Hua Hin, el equipo utiliz\u00f3 la playa de Khao Takiab para escenas relajadas junto al mar. La producci\u00f3n film\u00f3 en el ic\u00f3nico Cicada Market, donde la secuencia de la cita en el mercado nocturno, con sus c\u00e1lidas luces de hadas, artesan\u00edas hechas a mano y el bullicio del fin de semana, coincide con el aspecto caracter\u00edstico del mercado.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">14. The Package (2017)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-package-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84549\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-package-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-package-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-package-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-package-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>The Package<\/em> film\u00f3 partes de sus escenas de gira internacional en Tailandia desde finales de 2016 hasta principios de 2017. En Bangkok, el Aeropuerto Suvarnabhumi aparece exactamente como es, sirviendo como tel\u00f3n de fondo para secuencias de salida y llegada. Escenas adicionales fueron filmadas en el Millennium Hilton Bangkok, a lo largo del puente Taksin y alrededor de Soi Convent Road cerca de Sala Daeng BTS, donde la producci\u00f3n utiliz\u00f3 la atm\u00f3sfera de la calle concurrida para cortes de personajes casuales y transiciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo tambi\u00e9n viaj\u00f3 a Pattaya, filmando en el muelle Bali Hai. Las vistas frente al mar y el \u00e1rea del puerto abierto proporcionaron tomas de establecimiento esc\u00e9nicas para el itinerario de viaje de los personajes.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">15. The K2 (2016)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-k2-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84540\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-k2-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-k2-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-k2-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-k2-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>The K2<\/em> llev\u00f3 a cabo su rodaje en Tailandia entre enero y febrero de 2016, utilizando Bangkok, Krabi y Phuket para construir el crudo tel\u00f3n de fondo del sudeste asi\u00e1tico para su arco inicial. En Bangkok, el rodaje se centr\u00f3 alrededor de los distritos de Sathorn y Silom. La emboscada en la f\u00e1brica abandonada del primer episodio fue filmada en realidad en un complejo de almacenes en Sathorn Soi 12 cerca del r\u00edo Chao Phraya. Silom Road y el \u00e1rea del Sky Bar representaron una ciudad an\u00f3nima del sudeste asi\u00e1tico, mientras que las secuencias nocturnas empapadas de ne\u00f3n, los tuk-tuks, los puestos callejeros y todo lo dem\u00e1s fueron capturados a lo largo de Soi Convent y Naradhiwas Rajanagarindra Road.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La producci\u00f3n luego se traslad\u00f3 al sur. En Krabi, el equipo film\u00f3 en Railay Beach West, utilizando tomas de drones de imponentes acantilados de piedra caliza y barcos de cola larga para crear visuales de viaje panor\u00e1micos. Phuket fue otra parada clave: Dibuk Road en el casco antiguo de Phuket aparece en escenas de transici\u00f3n callejera, y la base de operaciones del equipo fue el Hotel Pullman Panwa, que tambi\u00e9n alberg\u00f3 uno de los momentos junto a la piscina presentados en el programa.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">16. Healer (2014)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/healer-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84477\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/healer-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/healer-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/healer-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/healer-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Healer <\/em>film\u00f3 sus secuencias en Tailandia desde mediados de agosto hasta principios de septiembre de 2014, utilizando m\u00faltiples regiones para escenificar los trabajos encubiertos del drama y los flashbacks atmosf\u00e9ricos. En Bangkok, la producci\u00f3n rod\u00f3 alrededor de Soi Sathorn 11 y el \u00e1rea del puerto de Rama III, donde se cre\u00f3 la secuencia del \u00abtrabajo en el almac\u00e9n extranjero\u00bb. La escena de Healer escalando contenedores de env\u00edo fue filmada directamente en la zona industrial del puerto, mientras que un almac\u00e9n abandonado cerca de Soi Sathorn 11 proporcion\u00f3 cobertura interior. Tomas callejeras adicionales fueron capturadas en Yaowarat (Chinatown), mezcl\u00e1ndose con la est\u00e9tica del entorno criminal internacional del programa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuera de la capital, la Ciudad Antigua de Samut Prakan sirvi\u00f3 como tel\u00f3n de fondo para una escena de memoria clave. El departamento de arte utiliz\u00f3 m\u00e1quinas de niebla e iluminaci\u00f3n difusa para dar a la ubicaci\u00f3n su textura suave y on\u00edrica. El equipo tambi\u00e9n viaj\u00f3 a Krabi, donde Railay Beach (lado oeste) se utiliz\u00f3 para breves tomas esc\u00e9nicas y de transici\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">17. My Love from the Star (2013)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/my-love-from-the-star-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84504\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/my-love-from-the-star-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/my-love-from-the-star-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/my-love-from-the-star-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/my-love-from-the-star-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>My Love from the Star<\/em> film\u00f3 su arco de Tailandia entre julio y agosto de 2013, utilizando Bangkok y Phuket para dar vida a la \u00abescapada curativa\u00bb de Song-yi. En el Aeropuerto Suvarnabhumi, el drama film\u00f3 escenas reales de salida y llegada dentro del Concourse E, capturando el bullicio de los viajeros mientras ella vuela hacia su escape tropical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de las escenas principales se filmaron en Phuket. Cape Panwa y el lujoso Sri Panwa Resort sirvieron como el retiro de Song-yi, con la Villa #18 en el Ala Oeste utilizada para su estancia con vista al mar y momentos en el balc\u00f3n. Partes del casco antiguo de Phuket tambi\u00e9n aparecen, donde el equipo de producci\u00f3n instal\u00f3 vallas publicitarias de marcas coreanas para mantener la continuidad visual con los entornos anteriores de Se\u00fal. El espectacular mirador del Cabo Promthep completa la secuencia, dando al programa una de sus tomas de postal m\u00e1s reconocibles.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">18. The Fugitive: Plan B (2010)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fugitive-plan-b-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84531\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fugitive-plan-b-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fugitive-plan-b-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fugitive-plan-b-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/the-fugitive-plan-b-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>The Fugitive: Plan B<\/em> rod\u00f3 sus secuencias en Tailandia entre febrero y marzo de 2010, utilizando Bangkok, Pattaya y Phuket para construir su arco de acci\u00f3n. En Bangkok, el rodaje tuvo lugar alrededor de Surawong Road, Soi Convent y el \u00e1rea del Banyan Tree Hotel, donde secciones de Silom se transformaron en una cruda \u00abzona del mercado negro de Hong Kong\u00bb. La estaci\u00f3n de tren de Hua Lamphong y el \u00e1rea de Rama I tambi\u00e9n se utilizaron, con la estaci\u00f3n cerrada durante la noche para la producci\u00f3n a principios de marzo. A lo largo de la orilla del r\u00edo Chao Phraya cerca del muelle Asiatique, el equipo organiz\u00f3 explosiones pr\u00e1cticas en barcos bajo la supervisi\u00f3n de la Polic\u00eda Marina de Tailandia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La producci\u00f3n luego se traslad\u00f3 a Pattaya, capturando la atm\u00f3sfera de la vida nocturna en Walking Street y escenas frente al mar en el muelle Bali Hai. Phuket complet\u00f3 el arco, con escenas filmadas en Patong Beach y a lo largo de Patong Hill Road hacia Cabo Promthep, dando al episodio final de Tailandia su dram\u00e1tico tel\u00f3n de fondo costero.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">19. Full House (2004)<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/full-house-cover-image-1024x536.jpg\" alt=\"\" class=\"wp-image-84468\" srcset=\"https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/full-house-cover-image-1024x536.jpg 1024w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/full-house-cover-image-300x157.jpg 300w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/full-house-cover-image-768x402.jpg 768w, https:\/\/mbrellafilms.com\/wp-content\/uploads\/2025\/11\/full-house-cover-image.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Full House<\/em> film\u00f3 sus secuencias en Tailandia entre marzo y abril de 2004, utilizando Bangkok, Phuket y Koh Samui para construir el arco de escapada tropical del drama. En Bangkok, el Aeropuerto Suvarnabhumi aparece en las primeras escenas de la terminal antes de que la historia se traslade al sur, mientras que el Mandarin Oriental Bangkok se utiliz\u00f3 como el exterior del hotel junto al r\u00edo Chao Phraya durante la \u00abparada de transferencia de luna de miel\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Phuket aparece brevemente para inserciones de playa y transiciones esc\u00e9nicas, particularmente en Cabo Promthep y Kata Noi Beach, que se utilizaron como material de archivo entre las escenas principales de Koh Samui. La ic\u00f3nica villa costera de la pareja no era un resort en absoluto, sino una propiedad privada cerca de la playa de Laem Sor en la costa sur de Koh Samui, sirviendo como la ubicaci\u00f3n principal para la historia de la isla del programa.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mbrellafilms.com\/es\/insights\/korean-dramas-filmed-in-thailand\/#contact\">Learn More About Korean Drama Production in Thailand<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusi\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al final, el ascenso de Tailandia como un punto de acceso de K-dramas se reduce a la mezcla perfecta de belleza, versatilidad y fuerza y experiencia de la industria. Sus paisajes son diversos, proporcionando todo lo que un equipo de producci\u00f3n necesita, desde horizontes modernos hasta mercados antiguos, playas hasta monta\u00f1as escarpadas, villas italianas, hoteles de lujo y m\u00e1s. Con atractivos reembolsos e incentivos gubernamentales y la experiencia pr\u00e1ctica de empresas como Mbrella Films, no es sorprendente que m\u00e1s series coreanas contin\u00faen eligiendo Tailandia como su lugar de rodaje preferido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1 interesado en filmar producciones en Tailandia, somos una empresa de producci\u00f3n ubicada en Bangkok, lista para ayudarlo con la preproducci\u00f3n, producci\u00f3n y postproducci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00f3ngase en contacto con un productor hoy y reciba un presupuesto detallado en 24 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la d\u00e9cada de 2000, los K-dramas han explotado en Tailandia, y muchas productoras coreanas han elegido Tailandia como su destino de rodaje preferido debido a las diversas ubicaciones de filmaci\u00f3n del pa\u00eds y al atractivo reembolso en efectivo del 30%.<\/p>\n","protected":false},"author":15,"featured_media":84494,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"content-type":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-84748","insights","type-insights","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/insights\/84748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/users\/15"}],"version-history":[{"count":10,"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/insights\/84748\/revisions"}],"predecessor-version":[{"id":87738,"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/insights\/84748\/revisions\/87738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/media\/84494"}],"wp:attachment":[{"href":"https:\/\/mbrellafilms.com\/es\/wp-json\/wp\/v2\/media?parent=84748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}